{"id":28,"count":5436,"description":"","link":"https:\/\/danellaconsulting.net\/index.php\/category\/great-awakening\/","name":"Great Awakening","slug":"great-awakening","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/danellaconsulting.net\/index.php\/wp-json\/wp\/v2\/categories\/28","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/danellaconsulting.net\/index.php\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/danellaconsulting.net\/index.php\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/danellaconsulting.net\/index.php\/wp-json\/wp\/v2\/posts?categories=28"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}